{"id":1030,"date":"2024-01-11T15:03:00","date_gmt":"2024-01-11T23:03:00","guid":{"rendered":"https:\/\/www.margarethantiuk.com\/?page_id=1030"},"modified":"2024-12-03T15:08:06","modified_gmt":"2024-12-03T23:08:06","slug":"shades","status":"publish","type":"page","link":"https:\/\/www.margarethantiuk.com\/index.php\/shades\/","title":{"rendered":"Shades"},"content":{"rendered":"\n<h2 class=\"wp-block-heading has-text-align-left has-subtle-background-color has-text-color has-link-color wp-elements-13bb4f1350c2b1337cdcaefa67c2f9d9\" style=\"font-size:4em\">SHADES<\/h2>\n\n\n<style>.wp-block-kadence-advancedgallery.kb-gallery-wrap-id-1030_375e99-a4{margin-top:-32px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-advancedgallery .kb-gallery-type-masonry.kb-gallery-id-1030_375e99-a4{margin:-11px;}.kb-gallery-type-masonry.kb-gallery-id-1030_375e99-a4 .kadence-blocks-gallery-item{padding:11px;}.kb-gallery-id-1030_375e99-a4 .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-1030_375e99-a4 .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}@media all and (max-width: 767px){.wp-block-kadence-advancedgallery .kb-gallery-type-masonry.kb-gallery-id-1030_375e99-a4{margin:-6px;}.kb-gallery-type-masonry.kb-gallery-id-1030_375e99-a4 .kadence-blocks-gallery-item{padding:6px;}}<\/style><div class=\"kb-gallery-wrap-id-1030_375e99-a4 alignnone alignfull wp-block-kadence-advancedgallery\"><ul class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-masonry kb-masonry-init kb-gallery-id-1030_375e99-a4 kb-gallery-caption-style-bottom-hover kb-gallery-filter-none kb-gallery-magnific-init\" data-image-filter=\"none\" data-item-selector=\".kadence-blocks-gallery-item\" data-lightbox-caption=\"true\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\"><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1813-L.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:580px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:78%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1813-L-1024x802.jpg\" width=\"580\" height=\"454\" alt=\"\" data-full-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1813-L.jpg\" data-light-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1813-L.jpg\" data-id=\"1121\" class=\"wp-image-1121\" srcset=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1813-L-1024x802.jpg 1024w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1813-L-300x235.jpg 300w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1813-L-768x601.jpg 768w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1813-L-1200x939.jpg 1200w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1813-L.jpg 1533w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1814-R.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:580px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:77%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1814-R-1024x796.jpg\" width=\"580\" height=\"451\" alt=\"\" data-full-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1814-R.jpg\" data-light-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1814-R.jpg\" data-id=\"1120\" class=\"wp-image-1120\" srcset=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1814-R-1024x796.jpg 1024w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1814-R-300x233.jpg 300w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1814-R-768x597.jpg 768w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1814-R-1536x1195.jpg 1536w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1814-R-1200x933.jpg 1200w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1814-R.jpg 1543w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1801.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:580px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:76%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1801-1024x783.jpg\" width=\"580\" height=\"443\" alt=\"\" data-full-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1801.jpg\" data-light-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1801.jpg\" data-id=\"1128\" class=\"wp-image-1128\" srcset=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1801-1024x783.jpg 1024w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1801-300x229.jpg 300w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1801-768x587.jpg 768w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1801-1536x1174.jpg 1536w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1801-1200x917.jpg 1200w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1801.jpg 1570w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1790.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:580px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:105%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1790-971x1024.jpg\" width=\"580\" height=\"612\" alt=\"\" data-full-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1790.jpg\" data-light-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1790.jpg\" data-id=\"1127\" class=\"wp-image-1127\" srcset=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1790-971x1024.jpg 971w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1790-285x300.jpg 285w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1790-768x810.jpg 768w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1790.jpg 1200w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1469.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:580px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:98%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1469-1024x1012.jpg\" width=\"580\" height=\"573\" alt=\"\" data-full-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1469.jpg\" data-light-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1469.jpg\" data-id=\"1126\" class=\"wp-image-1126\" srcset=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1469-1024x1012.jpg 1024w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1469-300x297.jpg 300w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1469-768x759.jpg 768w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1469-1200x1186.jpg 1200w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1469.jpg 1214w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1870.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:580px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:101%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1870-1014x1024.jpg\" width=\"580\" height=\"586\" alt=\"\" data-full-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1870.jpg\" data-light-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1870.jpg\" data-id=\"1125\" class=\"wp-image-1125\" srcset=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1870-1014x1024.jpg 1014w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1870-297x300.jpg 297w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1870-768x776.jpg 768w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1870.jpg 1200w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1467.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:580px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:98%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1467-1024x1005.jpg\" width=\"580\" height=\"569\" alt=\"\" data-full-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1467.jpg\" data-light-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1467.jpg\" data-id=\"1124\" class=\"wp-image-1124\" srcset=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1467-1024x1005.jpg 1024w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1467-300x294.jpg 300w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1467-768x754.jpg 768w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1467-1200x1177.jpg 1200w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1467.jpg 1223w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1788.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:580px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:98%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1788-1024x1014.jpg\" width=\"580\" height=\"574\" alt=\"\" data-full-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1788.jpg\" data-light-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1788.jpg\" data-id=\"1122\" class=\"wp-image-1122\" srcset=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1788-1024x1014.jpg 1024w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1788-300x297.jpg 300w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1788-768x760.jpg 768w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1788-1200x1188.jpg 1200w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1788.jpg 1212w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1817.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:580px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:103%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1817-986x1024.jpg\" width=\"580\" height=\"602\" alt=\"\" data-full-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1817.jpg\" data-light-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1817.jpg\" data-id=\"1123\" class=\"wp-image-1123\" srcset=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1817-986x1024.jpg 986w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1817-289x300.jpg 289w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1817-768x797.jpg 768w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/12\/shades-img_1817.jpg 1200w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7640.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:767px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:133%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7640-767x1024.jpg\" width=\"767\" height=\"1024\" alt=\"\" data-full-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7640.jpg\" data-light-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7640.jpg\" data-id=\"988\" class=\"wp-image-988\" srcset=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7640-767x1024.jpg 767w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7640-225x300.jpg 225w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7640-768x1025.jpg 768w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7640.jpg 1200w\" sizes=\"auto, (max-width: 767px) 100vw, 767px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7634.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:580px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:100%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7634-1024x1024.jpg\" width=\"580\" height=\"580\" alt=\"\" data-full-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7634.jpg\" data-light-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7634.jpg\" data-id=\"987\" class=\"wp-image-987\" srcset=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7634-1024x1024.jpg 1024w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7634-300x300.jpg 300w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7634-150x150.jpg 150w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7634-768x767.jpg 768w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7634.jpg 1201w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7629.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:580px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:102%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7629-1004x1024.jpg\" width=\"580\" height=\"592\" alt=\"\" data-full-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7629.jpg\" data-light-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7629.jpg\" data-id=\"986\" class=\"wp-image-986\" srcset=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7629-1004x1024.jpg 1004w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7629-294x300.jpg 294w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7629-768x783.jpg 768w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7629.jpg 1200w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7624.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:580px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:100%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7624-1024x1024.jpg\" width=\"580\" height=\"580\" alt=\"\" data-full-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7624.jpg\" data-light-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7624.jpg\" data-id=\"985\" class=\"wp-image-985\" srcset=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7624-1024x1024.jpg 1024w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7624-300x300.jpg 300w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7624-150x150.jpg 150w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7624-768x769.jpg 768w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7624.jpg 1200w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7051.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:580px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:101%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7051-1013x1024.jpg\" width=\"580\" height=\"586\" alt=\"\" data-full-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7051.jpg\" data-light-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7051.jpg\" data-id=\"984\" class=\"wp-image-984\" srcset=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7051-1013x1024.jpg 1013w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7051-297x300.jpg 297w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7051-768x776.jpg 768w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_7051.jpg 1200w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_0934.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:580px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:75%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_0934-1024x772.jpg\" width=\"580\" height=\"437\" alt=\"\" data-full-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_0934.jpg\" data-light-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_0934.jpg\" data-id=\"983\" class=\"wp-image-983\" srcset=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_0934-1024x772.jpg 1024w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_0934-300x226.jpg 300w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_0934-768x579.jpg 768w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_0934-1536x1159.jpg 1536w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_0934-1200x905.jpg 1200w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_0934.jpg 1591w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_0930.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:580px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:97%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_0930-1024x1001.jpg\" width=\"580\" height=\"567\" alt=\"\" data-full-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_0930.jpg\" data-light-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_0930.jpg\" data-id=\"982\" class=\"wp-image-982\" srcset=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_0930-1024x1001.jpg 1024w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_0930-300x293.jpg 300w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_0930-768x750.jpg 768w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_0930-1200x1173.jpg 1200w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_0930.jpg 1228w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_0052.jpg\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:580px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:75%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_0052-1024x772.jpg\" width=\"580\" height=\"437\" alt=\"\" data-full-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_0052.jpg\" data-light-image=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_0052.jpg\" data-id=\"981\" class=\"wp-image-981\" srcset=\"https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_0052-1024x772.jpg 1024w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_0052-300x226.jpg 300w, https:\/\/www.margarethantiuk.com\/wp-content\/uploads\/2024\/01\/shades-IMG_0052.jpg 1591w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><\/ul><\/div>\n\n\n<p class=\"has-text-align-left\" style=\"font-size:18px\"><br><br><em>Please enquire for prices, availability and dimensions<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SHADES Please enquire for prices, availability and dimensions<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-1030","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.margarethantiuk.com\/index.php\/wp-json\/wp\/v2\/pages\/1030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.margarethantiuk.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.margarethantiuk.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.margarethantiuk.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.margarethantiuk.com\/index.php\/wp-json\/wp\/v2\/comments?post=1030"}],"version-history":[{"count":5,"href":"https:\/\/www.margarethantiuk.com\/index.php\/wp-json\/wp\/v2\/pages\/1030\/revisions"}],"predecessor-version":[{"id":1129,"href":"https:\/\/www.margarethantiuk.com\/index.php\/wp-json\/wp\/v2\/pages\/1030\/revisions\/1129"}],"wp:attachment":[{"href":"https:\/\/www.margarethantiuk.com\/index.php\/wp-json\/wp\/v2\/media?parent=1030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}